{"id":88678,"date":"2024-10-29T16:25:47","date_gmt":"2024-10-29T20:25:47","guid":{"rendered":"https:\/\/ui-hybrid.local\/a-memorable-encounter-with-a-miserable-cheeseburger\/"},"modified":"2024-10-29T16:25:47","modified_gmt":"2024-10-29T20:25:47","slug":"a-memorable-encounter-with-a-miserable-cheeseburger","status":"publish","type":"post","link":"https:\/\/upstateinternational.org\/pt\/a-memorable-encounter-with-a-miserable-cheeseburger\/","title":{"rendered":"Um Encontro Memor\u00e1vel com um Cheeseburger Miser\u00e1vel"},"content":{"rendered":"<p>Harrison Baer<\/p>\n\n\n\n<p><strong><em>Terapia Cognitivo-Comportamental: <\/em><\/strong><em>O processo de reprogramar o c\u00e9rebro para ver o copo meio cheio, em vez de meio vazio, oferecendo alegria em tempos de tristeza, clareza em momentos de calamidade, al\u00edvio em meio ao estresse e luz na escurid\u00e3o.<\/em><\/p>\n\n\n\n<p>H\u00e1 12 horas, comi o pior cheeseburger da minha vida. Os p\u00e3es eram como airbags cheios de farinha, o queijo tinha gosto de pl\u00e1stico industrializado e a carne? Horr\u00edvel. A refei\u00e7\u00e3o refletiu o dia que eu estava tendo.<\/p>\n\n\n\n<p>Eu tinha dormido apenas umas quatro horas, gra\u00e7as \u00e0 banda ao vivo da noite anterior \u2014 convenientemente localizada bem embaixo da minha beliche \u2014 que tocou sem parar at\u00e9 depois da meia-noite. Um despertador \u00e0s 6h30 da manh\u00e3 foi seguido por uma viagem de \u00f4nibus exaustiva de tr\u00eas horas, durante a qual nosso guia tur\u00edstico parecia determinado a frear a cada dez minutos. Para piorar tudo, a balsa para Iona foi cancelada.<\/p>\n\n\n\n<p>Foi a\u00ed que comi o pior cheeseburger da minha vida. Nesse momento, a op\u00e7\u00e3o mais f\u00e1cil era considerar o dia um fracasso. Eu era um amontoado de azar, sem dormir, tremendo e espirrando.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Narrativa 2<\/strong>: <em>\u00a0<\/em><strong><em>Na mesma manh\u00e3, nas mesmas circunst\u00e2ncias e contada pela mesma pessoa \u2013\u00a0<\/em><\/strong><\/p>\n\n\n\n<p>No s\u00e1bado passado, acordei ao raiar do dia e sa\u00ed para a varanda do meu charmoso hotel. Contemplei pacientemente a costa escocesa, enquanto uma brisa fresca e suave acariciava meu rosto. Com o nascer do sol, ele iluminou gradualmente o porto \u00e0 minha frente. A \u00e1gua negra do mar ganhou um tom verde-esmeralda, enquanto o c\u00e9u escuro se aqueceu para um azul-beb\u00ea suave. Balsas antigas e veleiros r\u00fasticos deslizavam lentamente para dentro e para fora da costa rochosa. A vista era digna de uma pintura \u2014 uma que, se pintada, estaria no Louvre.<\/p>\n\n\n\n<p>Em seguida, veio a balsa para Mull, uma ilha consider\u00e1vel a leste da Esc\u00f3cia continental. L\u00e1 fora, no conv\u00e9s, o vento uivava, assobiava e chiava, e o sol banhava o c\u00e9u com um tom amarelo-dourado sob um manto de nuvens. Na metade do passeio, o barco adentrou uma paisagem de maravilhas. \u00c0 esquerda, um castelo medieval se erguia na costa de Mull, e \u00e0 direita, um arco-\u00edris radiante se estendia graciosamente do mar agitado, tendo como pano de fundo uma fileira de montanhas imponentes, dignas de Senhor dos An\u00e9is.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Ambas as hist\u00f3rias s\u00e3o verdadeiras e precisas. Naquela manh\u00e3, eu estava frustrado, exausto, com frio e mal-humorado, mas tamb\u00e9m encantado, alegre e maravilhado com a serenidade das Terras Altas da Esc\u00f3cia. O dia, com todas as suas falhas e perfei\u00e7\u00f5es, oscilava precariamente entre ser terr\u00edvel e maravilhoso. Apenas um fator determinaria se seria o primeiro ou o segundo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>H\u00e1 sessenta anos, o Dr. Aaron T. Beck desenvolveu a Terapia Cognitivo-Comportamental (TCC), uma abordagem revolucion\u00e1ria que ajuda a reprogramar o c\u00e9rebro para cultivar perspectivas positivas em vez de negativas. Beck cunhou o termo &quot;pensamentos autom\u00e1ticos&quot; \u2013 aquelas rea\u00e7\u00f5es r\u00e1pidas, instintivas e negativas que temos diante dos desafios. O objetivo da TCC \u00e9 transformar esses pensamentos autom\u00e1ticos prejudiciais em perspectivas construtivas e otimistas. Em vez de pensar &quot;Nossa viagem est\u00e1 arruinada&quot;, a TCC diz: &quot;Temos uma nova aventura inesperada pela frente&quot;.\u201c<\/p>\n\n\n\n<p>De volta ao dia de altos e baixos intermin\u00e1veis. A segunda balsa tinha acabado de ser cancelada e, faminto, sa\u00ed para almo\u00e7ar. Fiz uma r\u00e1pida ora\u00e7\u00e3o a Deus, pedindo por uma reviravolta melhor. Ent\u00e3o veio aquele cheeseburger horr\u00edvel. Aquela abomina\u00e7\u00e3o p\u00fatrida que nem me pagando eu comeria de novo. Ainda me lembro do meu primeiro pensamento depois de dar a primeira mordida.<\/p>\n\n\n\n<p>\u201cEste \u00e9 o hamb\u00farguer mais nojento que j\u00e1 comi. Que dia horr\u00edvel.\u201d<\/p>\n\n\n\n<p>Mas naquele instante, parei para pensar. Ser\u00e1 que vou mesmo deixar um cheeseburger ruim arruinar meu dia? Naquele momento, lembrei-me do meu treinamento em Terapia Cognitivo-Comportamental. Disse a mim mesmo que n\u00e3o deixaria aquele cheeseburger estragar meu dia. Ainda era um bom dia.\u00a0<\/p>\n\n\n\n<p>Ap\u00f3s uma tarde decepcionante, nosso grupo voltou para a van e partiu para um castelo pr\u00f3ximo. Dez minutos depois de iniciarmos a viagem de \u00f4nibus, um grupo de talvez dez vacas das Terras Altas apareceu \u00e0 nossa esquerda. Os animais eram m\u00e1gicos, com seus chifres, parecendo sa\u00eddos diretamente de N\u00e1rnia. O guia estacionou o \u00f4nibus e alguns de n\u00f3s descemos para observar melhor as criaturas. Decidi confrontar a vaca e fui direto at\u00e9 ela. Me aproximei sorrateiramente at\u00e9 que o animal estivesse a meros tr\u00eas metros de dist\u00e2ncia. Se ele tivesse decidido me atacar, eu talvez conseguisse dar dois passos antes de ser mandado direto para o pronto-socorro. No entanto, ele permaneceu im\u00f3vel, e compartilhamos um sil\u00eancio reconfortante por dois bons minutos antes de nos separarmos.<\/p>\n\n\n\n<p>Naquele momento de total vulnerabilidade, uma onda de adrenalina percorreu meu corpo. Apesar do perigo da posi\u00e7\u00e3o e da sensa\u00e7\u00e3o de estar completamente fora de controle, o que me preenchia n\u00e3o era medo, mas sim uma sensa\u00e7\u00e3o de poder.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Acredito piamente que aquele cheeseburger foi enviado por alguma for\u00e7a divina para testar minha resist\u00eancia interior. Ele chegou num momento crucial, em que o resultado do meu dia podia pender para qualquer lado \u2014 para o sucesso ou para o desespero. Desenvolver uma energia positiva exigia uma for\u00e7a robusta para vencer os pensamentos negativos, instintivos e nocivos.<\/p>\n\n\n\n<p>Nem que me pagassem eu comeria aquele cheeseburger de novo, mas da pr\u00f3xima vez que eu der uma mordida em algo t\u00e3o ruim, n\u00e3o vou ficar bravo. Em vez disso, vou sorrir e dar uma risadinha, porque sei que estou prestes a ter um \u00f3timo dia.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":77168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mo_disable_npp":"","wds_primary_category":0,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-88678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/posts\/88678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/comments?post=88678"}],"version-history":[{"count":0,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/posts\/88678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/media\/77168"}],"wp:attachment":[{"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/media?parent=88678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/categories?post=88678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upstateinternational.org\/pt\/wp-json\/wp\/v2\/tags?post=88678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}